{"id":28,"date":"2020-12-24T09:16:53","date_gmt":"2020-12-24T09:16:53","guid":{"rendered":"https:\/\/demo.phlox.pro\/agency-digital-2\/?page_id=28"},"modified":"2024-09-25T08:23:11","modified_gmt":"2024-09-25T08:23:11","slug":"contact","status":"publish","type":"page","link":"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"28\" class=\"elementor elementor-28\">\n\t\t\t\t<div data-export-id=\"260-28-77d4faf\" class=\"aux-parallax-section elementor-element elementor-element-77d4faf e-flex e-con-boxed e-con e-parent\" data-id=\"77d4faf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d92fea8 e-con-full e-flex e-con e-child\" data-id=\"d92fea8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3d394f aux-appear-watch-animation aux-slide-from-bot elementor-widget elementor-widget-aux_modern_heading\" data-id=\"d3d394f\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">contact<\/h2><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-export-id=\"260-28-ac81f34\" class=\"aux-parallax-section elementor-element elementor-element-ac81f34 e-flex e-con-boxed e-con e-parent\" data-id=\"ac81f34\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7ce484c e-con-full e-flex e-con e-child\" data-id=\"7ce484c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be5c264 aux-appear-watch-animation aux-fade-in-up elementor-widget elementor-widget-aux_modern_heading\" data-id=\"be5c264\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h3 class=\"aux-modern-heading-primary\"><span>contact<\/span> us<\/h3><h2 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-highlight\">Please Get In Touch<\/span><\/h2><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a8715b aux-appear-watch-animation aux-fade-in-up elementor-widget elementor-widget-aux_contact_form\" data-id=\"1a8715b\" data-element_type=\"widget\" data-widget_type=\"aux_contact_form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-contact-form aux-parent-au6b17378a\">            <div class=\"aux-col-wrapper aux-no-gutter\">\n            <!-- @TODO - The output for element here -->\n\n            \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1413-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/agency-digital-2\/wp-json\/wp\/v2\/pages\/28#wpcf7-f1413-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1413\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.8\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1413-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"aux-nextto\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"text-17\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required aux-space\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name\" value=\"\" type=\"text\" name=\"text-17\" \/><\/span>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"text-374\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"subject\" value=\"\" type=\"text\" name=\"text-374\" \/><\/span>\n<\/div>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email-942\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"email-942\" \/><\/span>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-502\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\" name=\"textarea-502\"><\/textarea><\/span>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send Message\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\n            <\/div><!-- aux-col-wrapper -->\n    <\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f50d28a e-con-full e-flex e-con e-child\" data-id=\"f50d28a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc5e8a6 aux-appear-watch-animation aux-scale-up elementor-widget elementor-widget-aux_gmap\" data-id=\"dc5e8a6\" data-element_type=\"widget\" data-widget_type=\"aux_gmap.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-gmaps aux-parent-au1ba70fed\">\n    <div class=\"aux-col-wrapper aux-no-gutter\">\n        <div id=\"aux-map6a04c014160f1\" class=\"aux-map-wrapper \" style=\"height:720px\" ><\/div>\n\n        <script>\n            jQuery( function($) {\n                if(typeof GMaps != \"function\" || typeof google === \"undefined\"){\n                    console.info( \"Please add google map API key in theme options. https:\/\/developers.google.com\/maps\/documentation\/javascript\/\" );\n                    return;\n                }\n                var map = new GMaps({\n                    el: \"#aux-map6a04c014160f1\",\n                    lat:  52,\n                    lng:  14,\n                    zoom: 12,\n                    scrollwheel: 0,\n                                        mapTypeId: google.maps.MapTypeId.ROADMAP,\n                                        disableDefaultUI: true,\n                                        panControl : true\n                });\n\n                                map.addStyle({\n                    styledMapName:\"Auxin custom style map\",\n                    styles: [\n    {\n        \"featureType\": \"all\",\n        \"elementType\": \"labels\",\n        \"stylers\": [\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"all\",\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"saturation\": 36\n            },\n            {\n                \"color\": \"#000000\"\n            },\n            {\n                \"lightness\": 40\n            }\n        ]\n    },\n    {\n        \"featureType\": \"all\",\n        \"elementType\": \"labels.text.stroke\",\n        \"stylers\": [\n            {\n                \"visibility\": \"on\"\n            },\n            {\n                \"color\": \"#000000\"\n            },\n            {\n                \"lightness\": 16\n            }\n        ]\n    },\n    {\n        \"featureType\": \"all\",\n        \"elementType\": \"labels.icon\",\n        \"stylers\": [\n            {\n                \"visibility\": \"off\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"administrative\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#000000\"\n            },\n            {\n                \"lightness\": 20\n            }\n        ]\n    },\n    {\n        \"featureType\": \"administrative\",\n        \"elementType\": \"geometry.stroke\",\n        \"stylers\": [\n            {\n                \"color\": \"#000000\"\n            },\n            {\n                \"lightness\": 17\n            },\n            {\n                \"weight\": 1.2\n            }\n        ]\n    },\n    {\n        \"featureType\": \"administrative.country\",\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#e5c163\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"administrative.locality\",\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#c4c4c4\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"administrative.neighborhood\",\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#e5c163\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"landscape\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#000000\"\n            },\n            {\n                \"lightness\": 20\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#000000\"\n            },\n            {\n                \"lightness\": 21\n            },\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi.business\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.highway\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#e5c163\"\n            },\n            {\n                \"lightness\": \"0\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.highway\",\n        \"elementType\": \"geometry.stroke\",\n        \"stylers\": [\n            {\n                \"visibility\": \"off\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.highway\",\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#ffffff\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.highway\",\n        \"elementType\": \"labels.text.stroke\",\n        \"stylers\": [\n            {\n                \"color\": \"#e5c163\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.arterial\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#000000\"\n            },\n            {\n                \"lightness\": 18\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.arterial\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#575757\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.arterial\",\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#ffffff\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.arterial\",\n        \"elementType\": \"labels.text.stroke\",\n        \"stylers\": [\n            {\n                \"color\": \"#2c2c2c\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.local\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#000000\"\n            },\n            {\n                \"lightness\": 16\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.local\",\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#999999\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"transit\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#000000\"\n            },\n            {\n                \"lightness\": 19\n            }\n        ]\n    },\n    {\n        \"featureType\": \"water\",\n        \"elementType\": \"geometry\",\n        \"stylers\": [\n            {\n                \"color\": \"#000000\"\n            },\n            {\n                \"lightness\": 17\n            }\n        ]\n    }\n],\n                    mapTypeId: \"aux_map_style\"\n                });\n\n                map.setStyle(\"aux_map_style\");\n                                map.addMarker({\n                                        lat : 52,\n                    lng : 14,\n                                            icon: \"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-content\/uploads\/sites\/260\/2021\/01\/location-on-map-icon.svg\"\n                    \n                });\n           });\n\n        <\/script>\n\n    <\/div><!-- aux-col-wrapper -->\n\n<\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-export-id=\"260-28-240a781\" class=\"aux-parallax-section elementor-element elementor-element-240a781 e-flex e-con-boxed e-con e-parent\" data-id=\"240a781\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fb16980 e-con-full e-flex e-con e-child\" data-id=\"fb16980\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13c6ef9 aux-appear-watch-animation aux-fade-in-left-1 elementor-widget elementor-widget-aux_text\" data-id=\"13c6ef9\" data-element_type=\"widget\" data-widget_type=\"aux_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-text aux-parent-au80bbc883\">        <div class=\"aux-widget-advanced-text aux-wrap-style-simple aux-ico-pos-top aux-text-center aux-text-resp- aux-text-color-dark aux-text-widget-bg-center  \" >\n        \n                            <div class=\"aux-text-widget-header \"  >\n                        <div class=\"aux-ico-box aux-ico-large aux-ico-clear \">\n                                                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"51\" height=\"60\" viewBox=\"0 0 51 60\">\n  <g transform=\"translate(-413.5 -2)\">\n    <path d=\"M29,2h.1A25.514,25.514,0,0,1,54.5,27.566v.279c-.189,10.035-6.222,18.36-11.25,23.58a61.862,61.862,0,0,1-4.521,4.26,2.238,2.238,0,0,1-2.907-3.4,57.431,57.431,0,0,0,4.2-3.96c4.47-4.638,9.837-11.976,10-20.559A21.083,21.083,0,0,0,29.081,6.47H29A21.034,21.034,0,0,0,7.979,27.38a27.36,27.36,0,0,0,5.58,15.678A67.084,67.084,0,0,0,29.513,57.89a2.237,2.237,0,0,1-2.445,3.747A71.945,71.945,0,0,1,9.98,45.752,31.821,31.821,0,0,1,3.5,27.539,25.548,25.548,0,0,1,29,2ZM23.765,27.842a5.226,5.226,0,1,0,5.226-5.22,2.238,2.238,0,1,1,0-4.47,9.69,9.69,0,1,1-9.7,9.69,2.239,2.239,0,1,1,4.479,0Z\" transform=\"translate(410)\" fill=\"#ffbd10\" fill-rule=\"evenodd\" \/>\n  <\/g>\n<\/svg>                                                    <\/div>\n                <\/div>\n            \n            <div class=\"aux-text-inner aux-text-widget-content\">\n                                <h4 class=\"col-title\">Address<\/h4>\n                                <div class=\"widget-content\">\n                                        <p>Patricia Amedee 4401 Waldeck Street Grapevine Nashville, Tx 76051<\/p>                <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"aux-text-widget-footer\">\n                <div class=\"aux-border-shape-none \">\n                                <\/div>\n            <\/div>\n        \n<\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a653949 e-con-full e-flex e-con e-child\" data-id=\"a653949\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5482ddc aux-appear-watch-animation aux-fade-in-up-1 elementor-widget elementor-widget-aux_text\" data-id=\"5482ddc\" data-element_type=\"widget\" data-widget_type=\"aux_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-text aux-parent-aud32725c9\">        <div class=\"aux-widget-advanced-text aux-wrap-style-simple aux-ico-pos-top aux-text-center aux-text-resp- aux-text-color-dark aux-text-widget-bg-center  \" >\n        \n                            <div class=\"aux-text-widget-header \"  >\n                        <div class=\"aux-ico-box aux-ico-large aux-ico-clear \">\n                                                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60.499\" height=\"60.495\" viewBox=\"0 0 60.499 60.495\">\n  <g transform=\"translate(-2 -2.001)\">\n    <path d=\"M37.138,3.994A2.22,2.22,0,0,1,39.6,2.016,25.85,25.85,0,0,1,62.483,25.03a2.227,2.227,0,1,1-4.425.5A21.411,21.411,0,0,0,39.11,6.475a2.238,2.238,0,0,1-1.972-2.48ZM7.554,12.954c-1.528,2.117-1.422,4.834.221,8.47a2.251,2.251,0,0,1-1.1,2.97,2.22,2.22,0,0,1-2.949-1.113c-2.335-5.167-2.3-9.48.13-12.814.511-.868,6.165-8.173,11.455-7.822a6.822,6.822,0,0,1,4.25,2.142c1.4,1.373,7.29,8.585,7.762,10.878a7.969,7.969,0,0,1-1.385,5.772c-.786,1.382-1.062,1.972-.793,2.716a26.588,26.588,0,0,0,9.1,11.8,2.257,2.257,0,0,1,.517,3.134,2.22,2.22,0,0,1-3.107.52A31.108,31.108,0,0,1,20.981,25.765c-1.028-2.859.194-5,1.089-6.564.672-1.174,1.041-1.875.883-2.62A56.618,56.618,0,0,0,16.444,8a2.7,2.7,0,0,0-1.428-.877c-2-.094-6.473,4.187-7.463,5.832ZM41.645,38.863c1.664-1.053,3.945-2.486,6.839-1.885,2.272.472,9.432,6.4,10.8,7.816A6.869,6.869,0,0,1,61.407,49C61.6,54.5,54.268,60.264,53.43,60.748A9.293,9.293,0,0,1,47.849,62.5,16.632,16.632,0,0,1,40.9,60.739C31.2,56.673,16.526,43.521,8.28,31.449a2.254,2.254,0,0,1,.572-3.119,2.22,2.22,0,0,1,3.1.578c7.7,11.271,21.783,23.967,30.745,27.724,3.63,1.694,6.328,1.8,8.334.348,1.561-.956,6.011-5.406,5.929-7.72a2.936,2.936,0,0,0-.859-1.331c-1.712-1.764-7.45-6.138-8.651-6.594-.956-.191-1.93.378-3.43,1.325l-.771.484a2.223,2.223,0,0,1-3.055-.765,2.254,2.254,0,0,1,.756-3.082l.7-.433Zm5.917-13.125a2.229,2.229,0,1,0,4.374-.856A15.373,15.373,0,0,0,39.781,12.643a2.243,2.243,0,0,0-.853,4.4A10.911,10.911,0,0,1,47.561,25.737Z\" transform=\"translate(0 0)\" fill=\"#8811FF\" fill-rule=\"evenodd\" \/>\n  <\/g>\n<\/svg>                                                    <\/div>\n                <\/div>\n            \n            <div class=\"aux-text-inner aux-text-widget-content\">\n                                <h4 class=\"col-title\">Phone<\/h4>\n                                <div class=\"widget-content\">\n                                        <p>+99 (0) 101 0000 888<\/p><p>+99 (0) 101 0000 777<\/p>                <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"aux-text-widget-footer\">\n                <div class=\"aux-border-shape-none \">\n                                <\/div>\n            <\/div>\n        \n<\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c81a087 e-con-full e-flex e-con e-child\" data-id=\"c81a087\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f82a6cc aux-appear-watch-animation aux-fade-in-right-1 elementor-widget elementor-widget-aux_text\" data-id=\"f82a6cc\" data-element_type=\"widget\" data-widget_type=\"aux_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-text aux-parent-aued6ed7ed\">        <div class=\"aux-widget-advanced-text aux-wrap-style-simple aux-ico-pos-top aux-text-center aux-text-resp- aux-text-color-dark aux-text-widget-bg-center  \" >\n        \n                            <div class=\"aux-text-widget-header \"  >\n                        <div class=\"aux-ico-box aux-ico-large aux-ico-clear \">\n                                                                <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"60\" height=\"54\" viewBox=\"0 0 60 54\">\n  <g transform=\"translate(-2 -3)\">\n    <path d=\"M62,24.921a2.13,2.13,0,0,1-2.124,2.139l-.027-.054a2.115,2.115,0,0,1-1.5-.627,2.148,2.148,0,0,1-.621-1.512V20.538A13.317,13.317,0,0,0,44.591,7.3H19.409A13.319,13.319,0,0,0,6.272,20.535v18.93a13.315,13.315,0,0,0,13.137,13.23H44.591a13.317,13.317,0,0,0,13.137-13.23,2.147,2.147,0,0,1,4.272,0A17.526,17.526,0,0,1,44.591,57H19.409A17.5,17.5,0,0,1,2,39.465V20.535A17.474,17.474,0,0,1,19.409,3H44.591A17.527,17.527,0,0,1,62,20.538v4.38Zm-27.783,4.65,12.339-9.942h.027a2.132,2.132,0,1,1,2.652,3.339L36.9,32.94a8.523,8.523,0,0,1-10.746,0L13.778,22.968a2.175,2.175,0,0,1-.318-3.021,2.091,2.091,0,0,1,2.973-.318L28.9,29.571a4.282,4.282,0,0,0,5.31,0Z\" transform=\"translate(0 0)\" fill=\"#ff1713\" fill-rule=\"evenodd\" \/>\n  <\/g>\n<\/svg>                                                    <\/div>\n                <\/div>\n            \n            <div class=\"aux-text-inner aux-text-widget-content\">\n                                <h4 class=\"col-title\">Email<\/h4>\n                                <div class=\"widget-content\">\n                                        <p>Info@yourdomain.com Info@yourdomain.net<\/p>                <\/div>\n                            <\/div>\n        <\/div>\n                    <div class=\"aux-text-widget-footer\">\n                <div class=\"aux-border-shape-none \">\n                                <\/div>\n            <\/div>\n        \n<\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>contact contact us Please Get In Touch Address Patricia Amedee 4401 Waldeck Street Grapevine Nashville, Tx 76051 Phone +99 (0) 101 0000 888 +99 (0) 101 0000 777 Email Info@yourdomain.com Info@yourdomain.net<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/page-builder-content.php","meta":{"footnotes":""},"class_list":["post-28","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact - Digital Agency Dark - Phlox Elementor WordPress Theme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - Digital Agency Dark - Phlox Elementor WordPress Theme\" \/>\n<meta property=\"og:description\" content=\"contact contact us Please Get In Touch Address Patricia Amedee 4401 Waldeck Street Grapevine Nashville, Tx 76051 Phone +99 (0) 101 0000 888 +99 (0) 101 0000 777 Email Info@yourdomain.com Info@yourdomain.net\" \/>\n<meta property=\"og:url\" content=\"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Digital Agency Dark - Phlox Elementor WordPress Theme\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T08:23:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/\",\"url\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/\",\"name\":\"Contact - Digital Agency Dark - Phlox Elementor WordPress Theme\",\"isPartOf\":{\"@id\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/#website\"},\"datePublished\":\"2020-12-24T09:16:53+00:00\",\"dateModified\":\"2024-09-25T08:23:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/#website\",\"url\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/\",\"name\":\"Digital Agency Dark - Phlox Elementor WordPress Theme\",\"description\":\"Complete Elementor Demo - Phlox WordPress Theme\",\"publisher\":{\"@id\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/#organization\",\"name\":\"Digital Agency Dark - Phlox Elementor WordPress Theme\",\"url\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-content\/uploads\/sites\/260\/2020\/12\/logo-header.svg\",\"contentUrl\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-content\/uploads\/sites\/260\/2020\/12\/logo-header.svg\",\"caption\":\"Digital Agency Dark - Phlox Elementor WordPress Theme\"},\"image\":{\"@id\":\"https:\/\/demo.phlox.pro\/agency-digital-2\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - Digital Agency Dark - Phlox Elementor WordPress Theme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/","og_locale":"en_US","og_type":"article","og_title":"Contact - Digital Agency Dark - Phlox Elementor WordPress Theme","og_description":"contact contact us Please Get In Touch Address Patricia Amedee 4401 Waldeck Street Grapevine Nashville, Tx 76051 Phone +99 (0) 101 0000 888 +99 (0) 101 0000 777 Email Info@yourdomain.com Info@yourdomain.net","og_url":"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/","og_site_name":"Digital Agency Dark - Phlox Elementor WordPress Theme","article_modified_time":"2024-09-25T08:23:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/","url":"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/","name":"Contact - Digital Agency Dark - Phlox Elementor WordPress Theme","isPartOf":{"@id":"https:\/\/demo.phlox.pro\/agency-digital-2\/#website"},"datePublished":"2020-12-24T09:16:53+00:00","dateModified":"2024-09-25T08:23:11+00:00","breadcrumb":{"@id":"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/demo.phlox.pro\/agency-digital-2\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/demo.phlox.pro\/agency-digital-2\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/demo.phlox.pro\/agency-digital-2\/#website","url":"https:\/\/demo.phlox.pro\/agency-digital-2\/","name":"Digital Agency Dark - Phlox Elementor WordPress Theme","description":"Complete Elementor Demo - Phlox WordPress Theme","publisher":{"@id":"https:\/\/demo.phlox.pro\/agency-digital-2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/demo.phlox.pro\/agency-digital-2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/demo.phlox.pro\/agency-digital-2\/#organization","name":"Digital Agency Dark - Phlox Elementor WordPress Theme","url":"https:\/\/demo.phlox.pro\/agency-digital-2\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/demo.phlox.pro\/agency-digital-2\/#\/schema\/logo\/image\/","url":"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-content\/uploads\/sites\/260\/2020\/12\/logo-header.svg","contentUrl":"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-content\/uploads\/sites\/260\/2020\/12\/logo-header.svg","caption":"Digital Agency Dark - Phlox Elementor WordPress Theme"},"image":{"@id":"https:\/\/demo.phlox.pro\/agency-digital-2\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-json\/wp\/v2\/pages\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":4,"href":"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-json\/wp\/v2\/pages\/28\/revisions"}],"predecessor-version":[{"id":3665,"href":"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-json\/wp\/v2\/pages\/28\/revisions\/3665"}],"wp:attachment":[{"href":"https:\/\/demo.phlox.pro\/agency-digital-2\/wp-json\/wp\/v2\/media?parent=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}